{"id":6,"date":"2025-09-26T13:45:27","date_gmt":"2025-09-26T17:45:27","guid":{"rendered":"https:\/\/www.clarku.edu\/wellness-education\/?page_id=6"},"modified":"2025-09-26T15:52:09","modified_gmt":"2025-09-26T19:52:09","slug":"meet-the-team","status":"publish","type":"page","link":"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/","title":{"rendered":"Meet the Team"},"content":{"rendered":"<div class=\"clarku-people\"><div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/jennifer-krulisz-hossain\/\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_5002_Jennifer-Krulisz-Hos-e1756322256829-297x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Jennifer Krulisz Hossain\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/jennifer-krulisz-hossain\/\">Jennifer Krulisz-Hossain<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Education Graduate Assistant<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Wellness Ambassadors<\/h3>\n\n\n<div class=\"clarku-people\"><div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/julia-calisto\/\"><img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/211A8D82-4FAD-4136-8565-2E9D18A58562_Julia-Calisto-scaled-e1756322393723-257x300-1.jpeg\" class=\"u-photo  wp-post-image\" alt=\"Julia Calisto\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/julia-calisto\/\">Julia Calisto<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/karina-fischman\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/WA-pic-2_Karina-Fischman-300x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Karina Fischman\" srcset=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/WA-pic-2_Karina-Fischman-300x300-1.jpg 300w, https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/WA-pic-2_Karina-Fischman-300x300-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/karina-fischman\/\">Karina Fischman<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\"><\/p>\n\t\t<p class=\"email\"><a class=\"u-email\" href=\"mailto:Wellness Ambassador\">Wellness Ambassador<\/a><\/p>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/emma-head\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7618_Emma-Head-e1755278914814-300x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Emma Head\" srcset=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7618_Emma-Head-e1755278914814-300x300-1.jpg 300w, https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7618_Emma-Head-e1755278914814-300x300-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/emma-head\/\">Emma Head<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/taylor-hildebrandt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"287\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7173_Taylor-Hildebrandt-e1755277730338-287x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Taylor Hildebrandt\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/taylor-hildebrandt\/\">Taylor Hildebrandt<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/sarah-lucas\/\"><img loading=\"lazy\" decoding=\"async\" width=\"264\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_9617_Sarah-Lucas-e1755277696625-264x300-1.jpeg\" class=\"u-photo  wp-post-image\" alt=\"Sarah Lucas\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/sarah-lucas\/\">Sarah Lucas<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/tor-pepi\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_6033-2_Tory-Pepi-300x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Tor Pepi\" srcset=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_6033-2_Tory-Pepi-300x300-1.jpg 300w, https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_6033-2_Tory-Pepi-300x300-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/tor-pepi\/\">Tor Pepi<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/kurt-robbins\/\"><img loading=\"lazy\" decoding=\"async\" width=\"255\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_20250808_113750_Kurt-Robbins-scaled-e1755277628254-255x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Kurt Robbins\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/kurt-robbins\/\">Kurt Robbins<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/charlotte-scott\/\"><img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"300\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_0568_Charlotte-Scott-e1755277492922-296x300-1.jpg\" class=\"u-photo  wp-post-image\" alt=\"Charlotte Scott\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/charlotte-scott\/\">Charlotte Scott<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"people-card h-card has-thumbnail\">\n\t<div class=\"avatar\">\n\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/cora-voet\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"298\" src=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7012_Original_Cora-Voet-scaled-e1755277554922-300x298-1.jpeg\" class=\"u-photo  wp-post-image\" alt=\"Cora Voet\" srcset=\"https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7012_Original_Cora-Voet-scaled-e1755277554922-300x298-1.jpeg 300w, https:\/\/www.clarku.edu\/wellness-education\/wp-content\/uploads\/sites\/100\/IMG_7012_Original_Cora-Voet-scaled-e1755277554922-300x298-1-150x150.jpeg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\n\t<\/div>\n\t\n\t<div class=\"inside\">\n\n\t\t\t\t\t<h3 class=\"p-name\"><a href=\"https:\/\/www.clarku.edu\/wellness-education\/people\/cora-voet\/\">Cora Voet<\/a><\/h3>\n\t\t\n\t\t<p class=\"people-title p-job-title\">Wellness Ambassador<\/p>\n\t\t\n\t<\/div>\n\n\t\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wellness Ambassadors<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Meet the Team | Wellness Education | Clark University<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meet the Team\" \/>\n<meta property=\"og:description\" content=\"Wellness Ambassadors\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/\" \/>\n<meta property=\"og:site_name\" content=\"Wellness Education\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClarkUniversityWorcester\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T19:52:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@clarkuniversity\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/meet-the-team\\\/\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/meet-the-team\\\/\",\"name\":\"Meet the Team | Wellness Education | Clark University\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/#website\"},\"datePublished\":\"2025-09-26T17:45:27+00:00\",\"dateModified\":\"2025-09-26T19:52:09+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/meet-the-team\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/6#breadcrumbs\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":0,\"name\":\"ClarkU\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Wellness Education\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/#website\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/\",\"name\":\"Wellness Education\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clarku.edu\\\/wellness-education\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Meet the Team | Wellness Education | Clark University","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/","og_locale":"en_US","og_type":"article","og_title":"Meet the Team","og_description":"Wellness Ambassadors","og_url":"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/","og_site_name":"Wellness Education","article_publisher":"https:\/\/www.facebook.com\/ClarkUniversityWorcester","article_modified_time":"2025-09-26T19:52:09+00:00","twitter_card":"summary_large_image","twitter_site":"@clarkuniversity","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/","url":"https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/","name":"Meet the Team | Wellness Education | Clark University","isPartOf":{"@id":"https:\/\/www.clarku.edu\/wellness-education\/#website"},"datePublished":"2025-09-26T17:45:27+00:00","dateModified":"2025-09-26T19:52:09+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clarku.edu\/wellness-education\/meet-the-team\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/pages\/6#breadcrumbs","itemListElement":[{"@type":"ListItem","position":0,"name":"ClarkU","item":"https:\/\/www.clarku.edu\/"},{"@type":"ListItem","position":1,"name":"Wellness Education","item":"https:\/\/www.clarku.edu\/wellness-education"}]},{"@type":"WebSite","@id":"https:\/\/www.clarku.edu\/wellness-education\/#website","url":"https:\/\/www.clarku.edu\/wellness-education\/","name":"Wellness Education","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clarku.edu\/wellness-education\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":2,"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":95,"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/pages\/6\/revisions\/95"}],"wp:attachment":[{"href":"https:\/\/www.clarku.edu\/wellness-education\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}