{"id":382,"date":"2024-12-12T10:32:38","date_gmt":"2024-12-12T15:32:38","guid":{"rendered":"https:\/\/www.golive.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/"},"modified":"2026-05-12T20:07:00","modified_gmt":"2026-05-13T00:07:00","slug":"jaclyn-greenhalgh","status":"publish","type":"cu_faculty","link":"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/","title":{"rendered":"Jaclyn Greenhalgh"},"content":{"rendered":"","protected":false},"author":0,"featured_media":0,"parent":0,"template":"","meta":{"cu_faculty_f180_userid":"C70145451","cu_faculty_first_name":"Jaclyn","cu_faculty_last_name":"Greenhalgh","cu_faculty_employment_status":"Part Time","cu_faculty_rank":"Part-time Instructor","cu_faculty_position":"Part-time Instructor","cu_faculty_phone":"","cu_faculty_email":"JGreenhalgh@clarku.edu","cu_faculty_location":"","cu_faculty_about":"","cu_faculty_degrees":"<span>J.D. in ,<\/span> Northeastern University, 1998\n<span>B.A. in Political Science,<\/span> Syracuse University, 1988","cu_faculty_cv":"","cu_faculty_links":"[]","cu_faculty_scholarly_interests":"","cu_faculty_scholarly_works":"","cu_faculty_awards_and_grants":"","cu_faculty_title":"Part-time Instructor, SPS","cu_faculty_department":"SPS","cu_faculty_affiliated_departments":"SPS","footnotes":""},"cu_faculty_group":[],"cu_faculty_department":[34],"cu_faculty_position":[],"class_list":["post-382","cu_faculty","type-cu_faculty","status-publish","hentry","cu_faculty_department-sps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jaclyn Greenhalgh | Faculty<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jaclyn Greenhalgh\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/\" \/>\n<meta property=\"og:site_name\" content=\"Faculty\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:07:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/profiles\\\/jaclyn-greenhalgh\\\/\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/profiles\\\/jaclyn-greenhalgh\\\/\",\"name\":\"Jaclyn Greenhalgh | Faculty\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/#website\"},\"datePublished\":\"2024-12-12T15:32:38+00:00\",\"dateModified\":\"2026-05-13T00:07:00+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/profiles\\\/jaclyn-greenhalgh\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/wp-json\\\/wp\\\/v2\\\/cu_faculty\\\/382#breadcrumbs\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":0,\"name\":\"ClarkU\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Faculty\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profiles\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/wp-json\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Profiles\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/wp-json\\\/wp\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Profiles\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/wp-json\\\/wp\\\/v2\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Profiles\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/wp-json\\\/wp\\\/v2\\\/cu_faculty\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Profiles\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/wp-json\\\/wp\\\/v2\\\/cu_faculty\\\/382\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/#website\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/\",\"name\":\"Faculty\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clarku.edu\\\/faculty\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jaclyn Greenhalgh | Faculty","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/","og_locale":"en_US","og_type":"article","og_title":"Jaclyn Greenhalgh","og_url":"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/","og_site_name":"Faculty","article_modified_time":"2026-05-13T00:07:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/","url":"https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/","name":"Jaclyn Greenhalgh | Faculty","isPartOf":{"@id":"https:\/\/www.clarku.edu\/faculty\/#website"},"datePublished":"2024-12-12T15:32:38+00:00","dateModified":"2026-05-13T00:07:00+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clarku.edu\/faculty\/profiles\/jaclyn-greenhalgh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty\/382#breadcrumbs","itemListElement":[{"@type":"ListItem","position":0,"name":"ClarkU","item":"https:\/\/www.clarku.edu\/"},{"@type":"ListItem","position":1,"name":"Faculty","item":"https:\/\/www.clarku.edu\/faculty"},{"@type":"ListItem","position":2,"name":"Profiles","item":"https:\/\/www.clarku.edu\/faculty\/wp-json"},{"@type":"ListItem","position":3,"name":"Profiles","item":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp"},{"@type":"ListItem","position":4,"name":"Profiles","item":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2"},{"@type":"ListItem","position":5,"name":"Profiles","item":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty"},{"@type":"ListItem","position":6,"name":"Profiles","item":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty\/382"}]},{"@type":"WebSite","@id":"https:\/\/www.clarku.edu\/faculty\/#website","url":"https:\/\/www.clarku.edu\/faculty\/","name":"Faculty","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clarku.edu\/faculty\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty\/382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty"}],"about":[{"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/types\/cu_faculty"}],"version-history":[{"count":1,"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty\/382\/revisions"}],"predecessor-version":[{"id":420,"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty\/382\/revisions\/420"}],"wp:attachment":[{"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/media?parent=382"}],"wp:term":[{"taxonomy":"cu_faculty_group","embeddable":true,"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty_group?post=382"},{"taxonomy":"cu_faculty_department","embeddable":true,"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty_department?post=382"},{"taxonomy":"cu_faculty_position","embeddable":true,"href":"https:\/\/www.clarku.edu\/faculty\/wp-json\/wp\/v2\/cu_faculty_position?post=382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}