{"id":4862,"date":"2024-05-23T18:02:54","date_gmt":"2024-05-23T22:02:54","guid":{"rendered":"https:\/\/www.golive.clarku.edu\/events\/event\/art-talk-dana-hoey\/"},"modified":"2025-01-18T22:44:42","modified_gmt":"2025-01-19T03:44:42","slug":"art-talk-dana-hoey","status":"publish","type":"tribe_events","link":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/","title":{"rendered":"Art Talk: Dana Hoey"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3018 alignright\" src=\"https:\/\/www.clarku.edu\/events\/wp-content\/uploads\/sites\/7\/2025\/01\/Dana-Hoey.jpeg\" alt=\"Dana Hoey\" width=\"200\" height=\"300\" \/>Clark\u2019s MFA in Visual Arts program presents an Art Talk with visiting speaker Dana Hoey. A photographer who examines contemporary female identity through staged and directed photographs and videos, Hoey&#8217;s solo projects include those at MOCA Detroit, Hirshhorn Museum and Sculpture Park, D.C., Petzel Gallery, NY, and the Center for Art, Design and Visual Culture, UMB, Baltimore. Hoey is currently pursuing an MDiv at the Harvard Divinity School.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clark\u2019s MFA in Visual Arts program presents an Art Talk with visiting speaker Dana Hoey.<\/p>\n","protected":false},"author":1,"featured_media":4864,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"UTC+0","_EventStartDate":"2024-06-26 19:00:00","_EventEndDate":"2024-06-26 21:00:00","_EventStartDateUTC":"2024-06-26 19:00:00","_EventEndDateUTC":"2024-06-26 21:00:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"USD\t\t\t\t\t\t\tclass=","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[9],"event_department":[110],"class_list":["post-4862","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-arts-music-film","event_department-school-of-professional-studies","cat_arts-music-film"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Art Talk: Dana Hoey | Events<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art Talk: Dana Hoey\" \/>\n<meta property=\"og:description\" content=\"Clark\u2019s MFA in Visual Arts program presents an Art Talk with visiting speaker Dana Hoey.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/\" \/>\n<meta property=\"og:site_name\" content=\"Events\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-19T03:44:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clarku.edu\/events\/wp-content\/uploads\/sites\/7\/2025\/01\/\" \/>\n\t<meta property=\"og:image:width\" content=\"401\" \/>\n\t<meta property=\"og:image:height\" content=\"253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/event\\\/art-talk-dana-hoey\\\/\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/event\\\/art-talk-dana-hoey\\\/\",\"name\":\"Art Talk: Dana Hoey | Events\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/event\\\/art-talk-dana-hoey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/event\\\/art-talk-dana-hoey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/Dana-Hoey-e1718134351319.jpeg\",\"datePublished\":\"2024-05-23T22:02:54+00:00\",\"dateModified\":\"2025-01-19T03:44:42+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clarku.edu\\\/events\\\/event\\\/art-talk-dana-hoey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/event\\\/art-talk-dana-hoey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/Dana-Hoey-e1718134351319.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/Dana-Hoey-e1718134351319.jpeg\",\"width\":401,\"height\":253},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-json\\\/wp\\\/v2\\\/tribe_events\\\/4862#breadcrumbs\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":0,\"name\":\"ClarkU\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/events\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Event\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-json\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Event\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-json\\\/wp\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Event\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-json\\\/wp\\\/v2\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Event\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-json\\\/wp\\\/v2\\\/tribe_events\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Event\",\"item\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/wp-json\\\/wp\\\/v2\\\/tribe_events\\\/4862\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/#website\",\"url\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/\",\"name\":\"Events\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clarku.edu\\\/events\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Art Talk: Dana Hoey | Events","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/","og_locale":"en_US","og_type":"article","og_title":"Art Talk: Dana Hoey","og_description":"Clark\u2019s MFA in Visual Arts program presents an Art Talk with visiting speaker Dana Hoey.","og_url":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/","og_site_name":"Events","article_modified_time":"2025-01-19T03:44:42+00:00","og_image":[{"width":401,"height":253,"url":"https:\/\/www.clarku.edu\/events\/wp-content\/uploads\/sites\/7\/2025\/01\/","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/","url":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/","name":"Art Talk: Dana Hoey | Events","isPartOf":{"@id":"https:\/\/www.clarku.edu\/events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/#primaryimage"},"image":{"@id":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clarku.edu\/events\/wp-content\/uploads\/sites\/7\/2025\/01\/Dana-Hoey-e1718134351319.jpeg","datePublished":"2024-05-23T22:02:54+00:00","dateModified":"2025-01-19T03:44:42+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.clarku.edu\/events\/event\/art-talk-dana-hoey\/#primaryimage","url":"https:\/\/www.clarku.edu\/events\/wp-content\/uploads\/sites\/7\/2025\/01\/Dana-Hoey-e1718134351319.jpeg","contentUrl":"https:\/\/www.clarku.edu\/events\/wp-content\/uploads\/sites\/7\/2025\/01\/Dana-Hoey-e1718134351319.jpeg","width":401,"height":253},{"@type":"BreadcrumbList","@id":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events\/4862#breadcrumbs","itemListElement":[{"@type":"ListItem","position":0,"name":"ClarkU","item":"https:\/\/www.clarku.edu\/"},{"@type":"ListItem","position":1,"name":"Events","item":"https:\/\/www.clarku.edu\/events"},{"@type":"ListItem","position":2,"name":"Event","item":"https:\/\/www.clarku.edu\/events\/wp-json"},{"@type":"ListItem","position":3,"name":"Event","item":"https:\/\/www.clarku.edu\/events\/wp-json\/wp"},{"@type":"ListItem","position":4,"name":"Event","item":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2"},{"@type":"ListItem","position":5,"name":"Event","item":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events"},{"@type":"ListItem","position":6,"name":"Event","item":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events\/4862"}]},{"@type":"WebSite","@id":"https:\/\/www.clarku.edu\/events\/#website","url":"https:\/\/www.clarku.edu\/events\/","name":"Events","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clarku.edu\/events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events\/4862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events\/4862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/media\/4864"}],"wp:attachment":[{"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/media?parent=4862"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tags?post=4862"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/tribe_events_cat?post=4862"},{"taxonomy":"event_department","embeddable":true,"href":"https:\/\/www.clarku.edu\/events\/wp-json\/wp\/v2\/event_department?post=4862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}